{"id":25533,"date":"2024-08-06T15:32:08","date_gmt":"2024-08-06T12:02:08","guid":{"rendered":"https:\/\/accbazar.com\/mag\/?p=25533"},"modified":"2024-09-19T16:04:05","modified_gmt":"2024-09-19T12:34:05","slug":"comparison-of-boso-and-duolingo-plus-accounts","status":"publish","type":"post","link":"https:\/\/accbazar.com\/mag\/comparison-of-boso-and-duolingo-plus-accounts\/","title":{"rendered":"\u0645\u0642\u0627\u06cc\u0633\u0647 \u0627\u0634\u062a\u0631\u0627\u06a9 \u0628\u0648\u0633\u0648 \u0648 \u0627\u0634\u062a\u0631\u0627\u06a9 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u067e\u0644\u0627\u0633\u061b \u0642\u062f\u0631\u062a\u0645\u0646\u062f\u062a\u0631\u06cc\u0646 \u0627\u0628\u0632\u0627\u0631 \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0632\u0628\u0627\u0646 \u06a9\u062f\u0627\u0645 \u0627\u0633\u062a\u061f"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #36bf36;\">\u0645\u0642\u0627\u06cc\u0633\u0647 \u0627\u0634\u062a\u0631\u0627\u06a9 \u0628\u0648\u0633\u0648 \u0648 \u0627\u0634\u062a\u0631\u0627\u06a9 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u067e\u0644\u0627\u0633\u061b \u0642\u062f\u0631\u062a\u0645\u0646\u062f\u062a\u0631\u06cc\u0646 \u0627\u0628\u0632\u0627\u0631 \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0632\u0628\u0627\u0646 \u06a9\u062f\u0627\u0645 \u0627\u0633\u062a\u061f<\/span><\/p>\n<p style=\"text-align: justify;\">\u0627\u0645\u0631\u0648\u0632\u0647 \u0628\u0627 \u06af\u0648\u0634\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u0648 \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u060c \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0632\u0628\u0627\u0646 \u0628\u0633\u06cc\u0627\u0631 \u0633\u0627\u062f\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a! \u0627\u0645\u0627 \u0628\u0627 \u0647\u0645\u0647 \u0627\u06cc\u0646 \u0627\u0648\u0635\u0627\u0641\u060c \u0627\u0646\u062a\u062e\u0627\u0628 \u0628\u0631\u0646\u0627\u0645\u0647 \u0645\u0646\u0627\u0633\u0628 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u06af\u06cc\u062c\u200c\u06a9\u0646\u0646\u062f\u0647 \u0628\u0627\u0634\u062f. \u0627\u0645\u0627 \u0646\u06af\u0631\u0627\u0646 \u0646\u0628\u0627\u0634\u06cc\u062f! \u0645\u0627 \u062f\u0631 \u0627\u06a9\u0627\u0646\u062a \u0628\u0627\u0632\u0627\u0631\u060c <strong><a href=\"https:\/\/accbazar.com\">\u0641\u0631\u0648\u0634\u06af\u0627\u0647 \u062a\u062e\u0635\u0635\u06cc \u0641\u0631\u0648\u0634 \u0627\u06a9\u0627\u0646\u062a<\/a><\/strong> \u0647\u0627\u06cc \u0627\u0635\u06cc\u0644 \u0648 \u0642\u0627\u0646\u0648\u0646\u06cc\u060c \u062f\u0648 \u0628\u0631\u0646\u0627\u0645\u0647 \u0645\u062d\u0628\u0648\u0628 \u0622\u0645\u0648\u0632\u0634 \u0632\u0628\u0627\u0646 \u0631\u0627 \u0628\u0631\u0627\u06cc\u062a\u0627\u0646 \u0645\u0642\u0627\u06cc\u0633\u0647 \u06a9\u0631\u062f\u0647\u200c\u0627\u06cc\u0645. \u0628\u0648\u0633\u0648 \u0648 <strong><a href=\"https:\/\/accbazar.com\/product\/Duolingo-Plus\">\u0627\u0634\u062a\u0631\u0627\u06a9 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u067e\u0644\u0627\u0633<\/a><\/strong> \u062f\u0648 \u063a\u0648\u0644 \u0622\u0645\u0648\u0632\u0634 \u0632\u0628\u0627\u0646 \u062f\u0631 \u062d\u0627\u0644 \u062d\u0627\u0636\u0631. \u0627\u06cc\u0646 \u062f\u0648 \u0628\u0631\u0646\u0627\u0645\u0647 \u0628\u0627 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062c\u0630\u0627\u0628 \u0648 \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc\u060c \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0632\u0628\u0627\u0646 \u0631\u0627 \u0628\u0633\u06cc\u0627\u0631 \u0622\u0633\u0627\u0646 \u0648 \u0633\u0631\u06af\u0631\u0645\u200c\u06a9\u0646\u0646\u062f\u0647 \u06a9\u0631\u062f\u0647 \u0627\u0646\u062f. \u0686\u0647 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0632\u0628\u0627\u0646 \u0627\u0646\u06af\u0644\u06cc\u0633\u06cc \u0648 \u0627\u0633\u067e\u0627\u0646\u06cc\u0627\u06cc\u06cc \u0628\u0627\u0634\u06cc\u062f\u060c \u0686\u0647 \u0698\u0627\u067e\u0646\u06cc \u06cc\u0627 \u0647\u0631 \u0632\u0628\u0627\u0646 \u062f\u06cc\u06af\u0631\u06cc\u060c \u0627\u06cc\u0646 \u062f\u0648 \u0631\u0627\u0647\u200c\u062d\u0644\u200c\u0647\u0627\u06cc \u0639\u0627\u0644\u06cc \u0628\u0631\u0627\u06cc \u0627\u0631\u0627\u0626\u0647 \u0628\u0647 \u0634\u0645\u0627 \u062f\u0627\u0631\u0646\u062f. \u0628\u0627 \u0645\u0627 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0647\u0645\u0631\u0627\u0647 \u0628\u0627\u0634\u06cc\u062f \u062a\u0627 \u0627\u0634\u062a\u0631\u0627\u06a9 \u0628\u0648\u0633\u0648 \u0648 \u0627\u0634\u062a\u0631\u0627\u06a9 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u067e\u0644\u0627\u0633 \u0631\u0627 \u0645\u0642\u0627\u06cc\u0633\u0647 \u06a9\u0646\u06cc\u0645 \u0648 \u0628\u0628\u06cc\u0646\u06cc\u0645 \u06a9\u062f\u0627\u0645 \u06cc\u06a9 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0645\u0646\u0627\u0633\u0628\u200c\u062a\u0631 \u0627\u0633\u062a.<\/p>\n<figure id=\"attachment_25573\" aria-describedby=\"caption-attachment-25573\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-25573 size-full\" src=\"https:\/\/accbazar.com\/mag\/wp-content\/uploads\/2024\/08\/comparison-of-boso-and-duolingo-plus-accounts-1.jpg\" alt=\"\u062a\u0641\u0627\u0648\u062a \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648\" width=\"1200\" height=\"800\" srcset=\"https:\/\/accbazar.com\/mag\/wp-content\/uploads\/2024\/08\/comparison-of-boso-and-duolingo-plus-accounts-1.jpg 1200w, https:\/\/accbazar.com\/mag\/wp-content\/uploads\/2024\/08\/comparison-of-boso-and-duolingo-plus-accounts-1-300x200.jpg 300w, https:\/\/accbazar.com\/mag\/wp-content\/uploads\/2024\/08\/comparison-of-boso-and-duolingo-plus-accounts-1-1024x683.jpg 1024w, https:\/\/accbazar.com\/mag\/wp-content\/uploads\/2024\/08\/comparison-of-boso-and-duolingo-plus-accounts-1-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-25573\" class=\"wp-caption-text\">\u062a\u0641\u0627\u0648\u062a \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648<\/figcaption><\/figure>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_58 counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title \" >\u0622\u0646\u0686\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u062e\u0648\u0627\u0647\u06cc\u062f \u062e\u0648\u0627\u0646\u062f:<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\" role=\"button\"><label for=\"item-6a0412850b05d\" ><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #000000;color:#000000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #000000;color:#000000\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input aria-label=\"Toggle\" aria-label=\"item-6a0412850b05d\"  type=\"checkbox\" id=\"item-6a0412850b05d\"><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/accbazar.com\/mag\/comparison-of-boso-and-duolingo-plus-accounts\/#%D8%AA%D9%81%D8%A7%D9%88%D8%AA_%D8%A8%D9%88%D8%B3%D9%88_%D9%88_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88\" title=\"\u062a\u0641\u0627\u0648\u062a \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648\">\u062a\u0641\u0627\u0648\u062a \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/accbazar.com\/mag\/comparison-of-boso-and-duolingo-plus-accounts\/#%D8%AA%D9%81%D8%A7%D9%88%D8%AA_%D8%A7%D8%B4%D8%AA%D8%B1%D8%A7%DA%A9_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88_%D9%BE%D9%84%D8%A7%D8%B3_%D9%88_%D8%A7%D8%B4%D8%AA%D8%B1%D8%A7%DA%A9_%D8%A8%D9%88%D8%B3%D9%88\" title=\"\u062a\u0641\u0627\u0648\u062a \u0627\u0634\u062a\u0631\u0627\u06a9 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u067e\u0644\u0627\u0633 \u0648 \u0627\u0634\u062a\u0631\u0627\u06a9 \u0628\u0648\u0633\u0648\">\u062a\u0641\u0627\u0648\u062a \u0627\u0634\u062a\u0631\u0627\u06a9 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u067e\u0644\u0627\u0633 \u0648 \u0627\u0634\u062a\u0631\u0627\u06a9 \u0628\u0648\u0633\u0648<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/accbazar.com\/mag\/comparison-of-boso-and-duolingo-plus-accounts\/#%D9%85%D9%82%D8%A7%DB%8C%D8%B3%D9%87_%D8%A8%D9%88%D8%B3%D9%88_%D9%88_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88\" title=\"\u0645\u0642\u0627\u06cc\u0633\u0647 \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648\">\u0645\u0642\u0627\u06cc\u0633\u0647 \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/accbazar.com\/mag\/comparison-of-boso-and-duolingo-plus-accounts\/#%D9%85%D9%82%D8%A7%DB%8C%D8%B3%D9%87_%D8%AA%D8%B9%D8%AF%D8%A7%D8%AF_%D8%B2%D8%A8%D8%A7%D9%86_%D9%87%D8%A7%DB%8C_%D8%A8%D9%88%D8%B3%D9%88_%D9%88_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88\" title=\"\u0645\u0642\u0627\u06cc\u0633\u0647 \u062a\u0639\u062f\u0627\u062f \u0632\u0628\u0627\u0646 \u0647\u0627\u06cc \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648\">\u0645\u0642\u0627\u06cc\u0633\u0647 \u062a\u0639\u062f\u0627\u062f \u0632\u0628\u0627\u0646 \u0647\u0627\u06cc \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/accbazar.com\/mag\/comparison-of-boso-and-duolingo-plus-accounts\/#%D9%85%D9%82%D8%A7%DB%8C%D8%B3%D9%87_%D8%B1%D9%88%D8%B4_%D8%AA%D8%AF%D8%B1%DB%8C%D8%B3_%D8%A8%D9%88%D8%B3%D9%88_%D9%88_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88\" title=\"\u0645\u0642\u0627\u06cc\u0633\u0647 \u0631\u0648\u0634 \u062a\u062f\u0631\u06cc\u0633 \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648\">\u0645\u0642\u0627\u06cc\u0633\u0647 \u0631\u0648\u0634 \u062a\u062f\u0631\u06cc\u0633 \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/accbazar.com\/mag\/comparison-of-boso-and-duolingo-plus-accounts\/#%D9%85%D9%82%D8%A7%DB%8C%D8%B3%D9%87_%D9%88%D8%A7%DA%98%DA%AF%D8%A7%D9%86_%D8%A8%D9%88%D8%B3%D9%88_%D9%88_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88\" title=\"\u0645\u0642\u0627\u06cc\u0633\u0647 \u0648\u0627\u0698\u06af\u0627\u0646 \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648\">\u0645\u0642\u0627\u06cc\u0633\u0647 \u0648\u0627\u0698\u06af\u0627\u0646 \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/accbazar.com\/mag\/comparison-of-boso-and-duolingo-plus-accounts\/#%D9%85%D9%82%D8%A7%DB%8C%D8%B3%D9%87_%DA%AF%D8%B1%D8%A7%D9%85%D8%B1_%D8%A8%D9%88%D8%B3%D9%88_%D9%88_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88\" title=\"\u0645\u0642\u0627\u06cc\u0633\u0647 \u06af\u0631\u0627\u0645\u0631 \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648\">\u0645\u0642\u0627\u06cc\u0633\u0647 \u06af\u0631\u0627\u0645\u0631 \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/accbazar.com\/mag\/comparison-of-boso-and-duolingo-plus-accounts\/#%D9%85%D9%82%D8%A7%DB%8C%D8%B3%D9%87_%D9%86%D9%88%D8%B4%D8%AA%D8%A7%D8%B1%DB%8C_%D8%A8%D9%88%D8%B3%D9%88_%D8%A8%D8%A7_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88\" title=\"\u0645\u0642\u0627\u06cc\u0633\u0647 \u0646\u0648\u0634\u062a\u0627\u0631\u06cc \u0628\u0648\u0633\u0648 \u0628\u0627 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648\">\u0645\u0642\u0627\u06cc\u0633\u0647 \u0646\u0648\u0634\u062a\u0627\u0631\u06cc \u0628\u0648\u0633\u0648 \u0628\u0627 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/accbazar.com\/mag\/comparison-of-boso-and-duolingo-plus-accounts\/#%D9%85%D9%82%D8%A7%DB%8C%D8%B3%D9%87_%D8%AF%D8%B1%DA%A9_%D9%85%D8%B7%D9%84%D8%A8_%D8%A8%D9%88%D8%B3%D9%88_%D9%88_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88\" title=\"\u0645\u0642\u0627\u06cc\u0633\u0647 \u062f\u0631\u06a9 \u0645\u0637\u0644\u0628 \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648\">\u0645\u0642\u0627\u06cc\u0633\u0647 \u062f\u0631\u06a9 \u0645\u0637\u0644\u0628 \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/accbazar.com\/mag\/comparison-of-boso-and-duolingo-plus-accounts\/#%D9%85%D9%82%D8%A7%DB%8C%D8%B3%D9%87_%D9%85%DA%A9%D8%A7%D9%84%D9%85%D9%87_%D8%A8%D9%88%D8%B3%D9%88_%D9%88_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88\" title=\"\u0645\u0642\u0627\u06cc\u0633\u0647 \u0645\u06a9\u0627\u0644\u0645\u0647 \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648\">\u0645\u0642\u0627\u06cc\u0633\u0647 \u0645\u06a9\u0627\u0644\u0645\u0647 \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/accbazar.com\/mag\/comparison-of-boso-and-duolingo-plus-accounts\/#%DA%AF%D9%88%D8%A7%D9%87%DB%8C_CEFR_%D8%A8%D9%88%D8%B3%D9%88_%D9%88_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88\" title=\"\u06af\u0648\u0627\u0647\u06cc CEFR \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648\">\u06af\u0648\u0627\u0647\u06cc CEFR \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648<\/a><ul class='ez-toc-list-level-4'><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/accbazar.com\/mag\/comparison-of-boso-and-duolingo-plus-accounts\/#%DA%AF%D9%88%D8%A7%D9%87%DB%8C_%D8%B2%D8%A8%D8%A7%D9%86_CEFR_%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\" title=\"\u06af\u0648\u0627\u0647\u06cc \u0632\u0628\u0627\u0646 CEFR \u0686\u06cc\u0633\u062a\u061f\">\u06af\u0648\u0627\u0647\u06cc \u0632\u0628\u0627\u0646 CEFR \u0686\u06cc\u0633\u062a\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/accbazar.com\/mag\/comparison-of-boso-and-duolingo-plus-accounts\/#%D8%A7%D9%87%D9%85%DB%8C%D8%AA_%DA%AF%D9%88%D8%A7%D9%87%DB%8C_CEFR\" title=\"\u0627\u0647\u0645\u06cc\u062a \u06af\u0648\u0627\u0647\u06cc CEFR\">\u0627\u0647\u0645\u06cc\u062a \u06af\u0648\u0627\u0647\u06cc CEFR<\/a><\/li><\/ul><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/accbazar.com\/mag\/comparison-of-boso-and-duolingo-plus-accounts\/#%D8%B3%D9%88%D8%A7%D9%84%D8%A7%D8%AA_%D9%85%D8%AA%D8%AF%D8%A7%D9%88%D9%84\" title=\"\u0633\u0648\u0627\u0644\u0627\u062a \u0645\u062a\u062f\u0627\u0648\u0644\">\u0633\u0648\u0627\u0644\u0627\u062a \u0645\u062a\u062f\u0627\u0648\u0644<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/accbazar.com\/mag\/comparison-of-boso-and-duolingo-plus-accounts\/#%D8%A8%D9%88%D8%B3%D9%88_%D8%A8%D8%B1%D8%A7%DB%8C_%D9%85%D8%A8%D8%AA%D8%AF%DB%8C%D8%A7%D9%86_%D8%A8%D9%87%D8%AA%D8%B1_%D8%A7%D8%B3%D8%AA_%DB%8C%D8%A7_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88%D8%9F\" title=\"\u0628\u0648\u0633\u0648 \u0628\u0631\u0627\u06cc \u0645\u0628\u062a\u062f\u06cc\u0627\u0646 \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u06cc\u0627 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648\u061f\">\u0628\u0648\u0633\u0648 \u0628\u0631\u0627\u06cc \u0645\u0628\u062a\u062f\u06cc\u0627\u0646 \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u06cc\u0627 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/accbazar.com\/mag\/comparison-of-boso-and-duolingo-plus-accounts\/#%D8%A8%D9%88%D8%B3%D9%88_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%B3%D8%B7%D9%88%D8%AD_%D9%BE%DB%8C%D8%B4%D8%B1%D9%81%D8%AA%D9%87%E2%80%8C_%D8%A8%D9%87%D8%AA%D8%B1_%D8%A7%D8%B3%D8%AA_%DB%8C%D8%A7_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88%D8%9F\" title=\"\u0628\u0648\u0633\u0648 \u0628\u0631\u0627\u06cc \u0633\u0637\u0648\u062d \u067e\u06cc\u0634\u0631\u0641\u062a\u0647\u200c \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u06cc\u0627 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648\u061f\">\u0628\u0648\u0633\u0648 \u0628\u0631\u0627\u06cc \u0633\u0637\u0648\u062d \u067e\u06cc\u0634\u0631\u0641\u062a\u0647\u200c \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u06cc\u0627 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/accbazar.com\/mag\/comparison-of-boso-and-duolingo-plus-accounts\/#%DA%A9%D8%AF%D8%A7%D9%85_%DB%8C%DA%A9_%D9%85%D8%AD%D8%AA%D9%88%D8%A7%DB%8C_%D8%A2%D9%85%D9%88%D8%B2%D8%B4%DB%8C_%D9%85%D8%AA%D9%86%D9%88%D8%B9%E2%80%8C%D8%AA%D8%B1%DB%8C_%D8%AF%D8%A7%D8%B1%D8%AF%D8%8C_%D8%A8%D9%88%D8%B3%D9%88_%DB%8C%D8%A7_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88%D8%9F\" title=\"\u06a9\u062f\u0627\u0645 \u06cc\u06a9 \u0645\u062d\u062a\u0648\u0627\u06cc \u0622\u0645\u0648\u0632\u0634\u06cc \u0645\u062a\u0646\u0648\u0639\u200c\u062a\u0631\u06cc \u062f\u0627\u0631\u062f\u060c \u0628\u0648\u0633\u0648 \u06cc\u0627 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648\u061f\">\u06a9\u062f\u0627\u0645 \u06cc\u06a9 \u0645\u062d\u062a\u0648\u0627\u06cc \u0622\u0645\u0648\u0632\u0634\u06cc \u0645\u062a\u0646\u0648\u0639\u200c\u062a\u0631\u06cc \u062f\u0627\u0631\u062f\u060c \u0628\u0648\u0633\u0648 \u06cc\u0627 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/accbazar.com\/mag\/comparison-of-boso-and-duolingo-plus-accounts\/#%D8%A8%D9%88%D8%B3%D9%88_%D8%AA%D8%B9%D8%A7%D9%85%D9%84_%D8%A8%D8%A7_%D8%B2%D8%A8%D8%A7%D9%86%E2%80%8C%D8%A2%D9%85%D9%88%D8%B2%D8%A7%D9%86_%D8%AF%DB%8C%DA%AF%D8%B1_%D8%B1%D8%A7_%D8%A8%D9%87%D8%AA%D8%B1_%D9%81%D8%B1%D8%A7%D9%87%D9%85_%D9%85%DB%8C%E2%80%8C%DA%A9%D9%86%D8%AF_%DB%8C%D8%A7_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88%D8%9F\" title=\"\u0628\u0648\u0633\u0648 \u062a\u0639\u0627\u0645\u0644 \u0628\u0627 \u0632\u0628\u0627\u0646\u200c\u0622\u0645\u0648\u0632\u0627\u0646 \u062f\u06cc\u06af\u0631 \u0631\u0627 \u0628\u0647\u062a\u0631 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc\u200c\u06a9\u0646\u062f \u06cc\u0627 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648\u061f\">\u0628\u0648\u0633\u0648 \u062a\u0639\u0627\u0645\u0644 \u0628\u0627 \u0632\u0628\u0627\u0646\u200c\u0622\u0645\u0648\u0632\u0627\u0646 \u062f\u06cc\u06af\u0631 \u0631\u0627 \u0628\u0647\u062a\u0631 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc\u200c\u06a9\u0646\u062f \u06cc\u0627 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/accbazar.com\/mag\/comparison-of-boso-and-duolingo-plus-accounts\/#%D8%A2%DB%8C%D8%A7_%D8%A8%D9%88%D8%B3%D9%88_%D9%88_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88_%D8%B1%D8%A7%DB%8C%DA%AF%D8%A7%D9%86_%D9%87%D8%B3%D8%AA%D9%86%D8%AF_%D9%88_%DB%8C%D8%A7_%D9%86%DB%8C%D8%A7%D8%B2_%D8%A8%D9%87_%D9%BE%D8%B1%D8%AF%D8%A7%D8%AE%D8%AA_%D8%A7%D8%B4%D8%AA%D8%B1%D8%A7%DA%A9_%D8%AF%D8%A7%D8%B1%D9%86%D8%AF%D8%9F\" title=\"\u0622\u06cc\u0627 \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u0631\u0627\u06cc\u06af\u0627\u0646 \u0647\u0633\u062a\u0646\u062f \u0648 \u06cc\u0627 \u0646\u06cc\u0627\u0632 \u0628\u0647 \u067e\u0631\u062f\u0627\u062e\u062a \u0627\u0634\u062a\u0631\u0627\u06a9 \u062f\u0627\u0631\u0646\u062f\u061f\">\u0622\u06cc\u0627 \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u0631\u0627\u06cc\u06af\u0627\u0646 \u0647\u0633\u062a\u0646\u062f \u0648 \u06cc\u0627 \u0646\u06cc\u0627\u0632 \u0628\u0647 \u067e\u0631\u062f\u0627\u062e\u062a \u0627\u0634\u062a\u0631\u0627\u06a9 \u062f\u0627\u0631\u0646\u062f\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/accbazar.com\/mag\/comparison-of-boso-and-duolingo-plus-accounts\/#%DA%A9%D8%AF%D8%A7%D9%85_%DB%8C%DA%A9_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%A7%D9%81%D8%B1%D8%A7%D8%AF%DB%8C_%DA%A9%D9%87_%D9%88%D9%82%D8%AA_%DA%A9%D9%85%DB%8C_%D8%AF%D8%A7%D8%B1%D9%86%D8%AF_%D9%85%D9%86%D8%A7%D8%B3%D8%A8%E2%80%8C%D8%AA%D8%B1_%D8%A7%D8%B3%D8%AA%D8%8C_%D8%A8%D9%88%D8%B3%D9%88_%DB%8C%D8%A7_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88%D8%9F\" title=\"\u06a9\u062f\u0627\u0645 \u06cc\u06a9 \u0628\u0631\u0627\u06cc \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u0648\u0642\u062a \u06a9\u0645\u06cc \u062f\u0627\u0631\u0646\u062f \u0645\u0646\u0627\u0633\u0628\u200c\u062a\u0631 \u0627\u0633\u062a\u060c \u0628\u0648\u0633\u0648 \u06cc\u0627 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648\u061f\">\u06a9\u062f\u0627\u0645 \u06cc\u06a9 \u0628\u0631\u0627\u06cc \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u0648\u0642\u062a \u06a9\u0645\u06cc \u062f\u0627\u0631\u0646\u062f \u0645\u0646\u0627\u0633\u0628\u200c\u062a\u0631 \u0627\u0633\u062a\u060c \u0628\u0648\u0633\u0648 \u06cc\u0627 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648\u061f<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/accbazar.com\/mag\/comparison-of-boso-and-duolingo-plus-accounts\/#%D8%A7%DA%A9%D8%A7%D9%86%D8%AA_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88_%D9%BE%D9%84%D8%A7%D8%B3\" title=\"\u0627\u06a9\u0627\u0646\u062a \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u067e\u0644\u0627\u0633\">\u0627\u06a9\u0627\u0646\u062a \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u067e\u0644\u0627\u0633<\/a><\/li><\/ul><\/nav><\/div>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%AA%D9%81%D8%A7%D9%88%D8%AA_%D8%A8%D9%88%D8%B3%D9%88_%D9%88_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88\"><\/span><span style=\"color: #36bf36;\">\u062a\u0641\u0627\u0648\u062a \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">\u062a\u0635\u0648\u0631 \u06a9\u0646\u06cc\u062f \u062f\u0648 \u0645\u0639\u0644\u0645 \u062f\u0627\u0631\u06cc\u062f \u06a9\u0647 \u0647\u0631 \u062f\u0648 \u0627\u0632 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0627\u0633\u0627\u062a\u06cc\u062f \u0622\u0645\u0648\u0632\u0634 \u0632\u0628\u0627\u0646 \u0647\u0633\u062a\u0646\u062f. \u06cc\u06a9\u06cc \u0628\u0648\u0633\u0648 \u0627\u0633\u062a \u0648 \u062f\u06cc\u06af\u0631\u06cc \u062f\u0648\u0644\u06cc\u0646\u06af\u0648. \u0647\u0631 \u062f\u0648 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u0646\u062f \u0634\u0645\u0627 \u0631\u0627 \u062f\u0631 \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0632\u0628\u0627\u0646 \u06cc\u0627\u0631\u06cc \u06a9\u0646\u0646\u062f\u060c \u0627\u0645\u0627 \u0647\u0631 \u06a9\u062f\u0627\u0645 \u0631\u0648\u0634 \u062a\u062f\u0631\u06cc\u0633 \u062e\u0627\u0635 \u062e\u0648\u062f \u0631\u0627 \u062f\u0627\u0631\u0646\u062f.<\/p>\n<p style=\"text-align: justify;\">\u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u0647\u0631 \u062f\u0648 \u0645\u0639\u062a\u0642\u062f\u0646\u062f \u06a9\u0647 \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0628\u0627\u06cc\u062f \u0633\u0631\u06af\u0631\u0645\u200c\u06a9\u0646\u0646\u062f\u0647 \u0628\u0627\u0634\u062f. \u0622\u0646\u0647\u0627 \u0628\u0627\u0632\u06cc\u200c\u0647\u0627 \u0648 \u0686\u0627\u0644\u0634\u200c\u0647\u0627\u06cc \u062c\u0630\u0627\u0628\u06cc \u0637\u0631\u0627\u062d\u06cc \u0645\u06cc \u06a9\u0646\u0646\u062f \u062a\u0627 \u0634\u0645\u0627 \u0628\u0627 \u0644\u0630\u062a \u0632\u0628\u0627\u0646 \u0631\u0627 \u06cc\u0627\u062f \u0628\u06af\u06cc\u0631\u06cc\u062f! \u0627\u0645\u0627 \u0647\u0631 \u06a9\u062f\u0627\u0645 \u0634\u062e\u0635\u06cc\u062a \u0645\u0646\u062d\u0635\u0631 \u0628\u0647 \u0641\u0631\u062f \u062e\u0648\u062f \u0631\u0627 \u062f\u0627\u0631\u0646\u062f. \u0628\u0648\u0633\u0648 \u0645\u062b\u0644 \u06cc\u06a9 \u0645\u0639\u0644\u0645 \u062e\u0635\u0648\u0635\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0631\u0648\u0634 \u062a\u062f\u0631\u06cc\u0633 \u0631\u0627 \u06a9\u0627\u0645\u0644\u0627\u064b \u0628\u0627 \u0646\u06cc\u0627\u0632\u0647\u0627\u06cc \u0634\u0645\u0627 \u062a\u0637\u0628\u06cc\u0642 \u0645\u06cc\u200c\u062f\u0647\u062f. \u062f\u0631 \u0645\u0642\u0627\u0628\u0644\u060c \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u0628\u06cc\u0634\u062a\u0631 \u0634\u0628\u06cc\u0647 \u06cc\u06a9 \u0645\u0639\u0644\u0645 \u0645\u062d\u0628\u0648\u0628 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0627 \u062a\u0645\u0631\u06cc\u0646\u200c\u0647\u0627\u06cc \u06a9\u0648\u062a\u0627\u0647 \u0648 \u0645\u0646\u0638\u0645 \u0634\u0645\u0627 \u0631\u0627 \u0628\u0647 \u0686\u0627\u0644\u0634 \u0645\u06cc\u200c\u06a9\u0634\u062f.<\/p>\n<p style=\"text-align: justify;\">\u0628\u0648\u0633\u0648 \u0639\u0645\u06cc\u0642\u200c\u062a\u0631 \u062a\u062f\u0631\u06cc\u0633 \u0645\u06cc \u06a9\u0646\u062f \u0648 \u062c\u0632\u0626\u06cc\u0627\u062a \u0628\u06cc\u0634\u062a\u0631\u06cc \u0631\u0627 \u067e\u0648\u0634\u0634 \u0645\u06cc\u200c\u062f\u0647\u062f\u060c \u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u0631\u0648\u06cc \u0645\u0641\u0627\u0647\u06cc\u0645 \u0627\u0635\u0644\u06cc \u062a\u0645\u0631\u06a9\u0632 \u062f\u0627\u0631\u062f.<\/p>\n<figure id=\"attachment_25574\" aria-describedby=\"caption-attachment-25574\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-25574 size-full\" src=\"https:\/\/accbazar.com\/mag\/wp-content\/uploads\/2024\/08\/comparison-of-boso-and-duolingo-plus-accounts-2.jpg\" alt=\"\u062a\u0641\u0627\u0648\u062a \u0627\u0634\u062a\u0631\u0627\u06a9 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u067e\u0644\u0627\u0633 \u0648 \u0627\u0634\u062a\u0631\u0627\u06a9 \u0628\u0648\u0633\u0648\" width=\"1200\" height=\"800\" srcset=\"https:\/\/accbazar.com\/mag\/wp-content\/uploads\/2024\/08\/comparison-of-boso-and-duolingo-plus-accounts-2.jpg 1200w, https:\/\/accbazar.com\/mag\/wp-content\/uploads\/2024\/08\/comparison-of-boso-and-duolingo-plus-accounts-2-300x200.jpg 300w, https:\/\/accbazar.com\/mag\/wp-content\/uploads\/2024\/08\/comparison-of-boso-and-duolingo-plus-accounts-2-1024x683.jpg 1024w, https:\/\/accbazar.com\/mag\/wp-content\/uploads\/2024\/08\/comparison-of-boso-and-duolingo-plus-accounts-2-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-25574\" class=\"wp-caption-text\">\u062a\u0641\u0627\u0648\u062a \u0627\u0634\u062a\u0631\u0627\u06a9 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u067e\u0644\u0627\u0633 \u0648 \u0627\u0634\u062a\u0631\u0627\u06a9 \u0628\u0648\u0633\u0648<\/figcaption><\/figure>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%AA%D9%81%D8%A7%D9%88%D8%AA_%D8%A7%D8%B4%D8%AA%D8%B1%D8%A7%DA%A9_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88_%D9%BE%D9%84%D8%A7%D8%B3_%D9%88_%D8%A7%D8%B4%D8%AA%D8%B1%D8%A7%DA%A9_%D8%A8%D9%88%D8%B3%D9%88\"><\/span><span style=\"color: #36bf36;\">\u062a\u0641\u0627\u0648\u062a \u0627\u0634\u062a\u0631\u0627\u06a9 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u067e\u0644\u0627\u0633 \u0648 \u0627\u0634\u062a\u0631\u0627\u06a9 \u0628\u0648\u0633\u0648<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0628\u0627 \u062a\u0645\u0627\u0645 \u0627\u06cc\u0646 \u062a\u0641\u0627\u0635\u06cc\u0644 \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u0639\u0644\u0645 \u0628\u06cc\u0646 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u0648 \u0628\u0648\u0633\u0648 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0686\u0627\u0644\u0634\u200c\u0628\u0631\u0627\u0646\u06af\u06cc\u0632 \u0628\u0627\u0634\u062f. \u062f\u0648 \u063a\u0648\u0644 \u062f\u0646\u06cc\u0627\u06cc \u0622\u0645\u0648\u0632\u0634 \u0632\u0628\u0627\u0646\u060c \u0647\u0631 \u06a9\u062f\u0627\u0645 \u0645\u0632\u0627\u06cc\u0627\u06cc \u0645\u0646\u062d\u0635\u0631 \u0628\u0647 \u0641\u0631\u062f\u06cc \u062f\u0627\u0631\u0646\u062f. \u0628\u0648\u0633\u0648 \u0628\u0627 \u0627\u0645\u06a9\u0627\u0646 \u06af\u0641\u062a\u06af\u0648\u06cc \u0632\u0646\u062f\u0647 \u0628\u0627 \u0645\u0639\u0644\u0645\u0627\u0646 \u0648 \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u0627\u0632 \u0633\u0648\u06cc \u06af\u0648\u06cc\u0634\u0648\u0631\u0627\u0646 \u0628\u0648\u0645\u06cc\u060c \u062a\u062c\u0631\u0628\u0647\u200c\u0627\u06cc \u0646\u0632\u062f\u06cc\u06a9 \u0628\u0647 \u06a9\u0644\u0627\u0633\u200c\u0647\u0627\u06cc \u062d\u0636\u0648\u0631\u06cc \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u0632 \u0633\u0648\u06cc \u062f\u06cc\u06af\u0631\u060c \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u0628\u0627 \u0631\u0648\u06cc\u06a9\u0631\u062f\u06cc \u0628\u0627\u0632\u06cc\u200c\u0648\u0627\u0631 \u0648 \u0633\u0631\u06af\u0631\u0645\u200c\u06a9\u0646\u0646\u062f\u0647\u060c \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0631\u0627 \u0628\u0647 \u0641\u0639\u0627\u0644\u06cc\u062a\u06cc \u0644\u0630\u062a\u200c\u0628\u062e\u0634 \u062a\u0628\u062f\u06cc\u0644 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a.<\/p>\n<p style=\"text-align: justify;\">\u0628\u0627 <strong><a href=\"https:\/\/accbazar.com\/product\/Busuu\">\u062e\u0631\u06cc\u062f \u0627\u06a9\u0627\u0646\u062a \u0628\u0648\u0633\u0648<\/a><\/strong> \u0627\u0632 \u0627\u06a9\u0627\u0646\u062a \u0628\u0627\u0632\u0627\u0631 \u0627\u0645\u06a9\u0627\u0646\u0627\u062a \u067e\u06cc\u0634\u0631\u0641\u062a\u0647\u200c\u0627\u06cc \u0631\u0627 \u062f\u0631 \u0627\u062e\u062a\u06cc\u0627\u0631 \u062e\u0648\u0627\u0647\u06cc\u062f \u062f\u0627\u0634\u062a \u0627\u0632 \u062c\u0645\u0644\u0647:<\/p>\n<ul style=\"text-align: justify;\">\n<li>\u0645\u06a9\u0627\u0644\u0645\u0647 \u0622\u0646\u0644\u0627\u06cc\u0646 \u0628\u0627 \u0645\u062f\u0631\u0633\u0627\u0646 \u0645\u062a\u062e\u0635\u0635<\/li>\n<li>\u0627\u0631\u062a\u0628\u0627\u0637 \u0628\u0627 \u06af\u0648\u06cc\u0634\u0648\u0631\u0627\u0646 \u0628\u0648\u0645\u06cc<\/li>\n<li>\u062f\u0633\u062a\u0631\u0633\u06cc \u0628\u0647 \u0637\u06cc\u0641 \u0648\u0633\u06cc\u0639\u06cc \u0627\u0632 \u0632\u0628\u0627\u0646\u200c\u0647\u0627<\/li>\n<li>\u0642\u0627\u0628\u0644\u06cc\u062a \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0622\u0641\u0644\u0627\u06cc\u0646<\/li>\n<li>\u0645\u062d\u06cc\u0637 \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0628\u062f\u0648\u0646 \u062a\u0628\u0644\u06cc\u063a\u0627\u062a<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">\u0628\u0627 \u062e\u0631\u06cc\u062f \u0627\u06a9\u0627\u0646\u062a \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u067e\u0644\u0627\u0633 \u0627\u0632 \u0627\u06a9\u0627\u0646\u062a \u0628\u0627\u0632\u0627\u0631 \u0627\u06cc\u0646 \u0645\u0632\u0627\u06cc\u0627\u06cc \u0642\u0627\u0628\u0644 \u062a\u0648\u062c\u0647 \u0631\u0627 \u06a9\u0633\u0628 \u062e\u0648\u0627\u0647\u06cc\u062f \u06a9\u0631\u062f:<\/p>\n<ul style=\"text-align: justify;\">\n<li>\u0627\u0631\u062a\u0642\u0627\u0621 \u0628\u0631\u0646\u0627\u0645\u0647<\/li>\n<li>\u0627\u0645\u06a9\u0627\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0622\u0641\u0644\u0627\u06cc\u0646<\/li>\n<li>\u0627\u0646\u0639\u0637\u0627\u0641\u200c\u067e\u0630\u06cc\u0631\u06cc \u062f\u0631 \u06af\u0630\u0631\u0627\u0646\u062f\u0646 \u062f\u0631\u0648\u0633<\/li>\n<li>\u062d\u0630\u0641 \u062a\u0628\u0644\u06cc\u063a\u0627\u062a<\/li>\n<li>\u0645\u0634\u0627\u0647\u062f\u0647 \u062f\u0642\u06cc\u0642 \u0645\u0633\u06cc\u0631 \u067e\u06cc\u0634\u0631\u0641\u062a<\/li>\n<\/ul>\n<figure id=\"attachment_25575\" aria-describedby=\"caption-attachment-25575\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-25575 size-full\" src=\"https:\/\/accbazar.com\/mag\/wp-content\/uploads\/2024\/08\/comparison-of-boso-and-duolingo-plus-accounts-3.jpg\" alt=\"\u0645\u0642\u0627\u06cc\u0633\u0647 \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648\" width=\"1200\" height=\"800\" srcset=\"https:\/\/accbazar.com\/mag\/wp-content\/uploads\/2024\/08\/comparison-of-boso-and-duolingo-plus-accounts-3.jpg 1200w, https:\/\/accbazar.com\/mag\/wp-content\/uploads\/2024\/08\/comparison-of-boso-and-duolingo-plus-accounts-3-300x200.jpg 300w, https:\/\/accbazar.com\/mag\/wp-content\/uploads\/2024\/08\/comparison-of-boso-and-duolingo-plus-accounts-3-1024x683.jpg 1024w, https:\/\/accbazar.com\/mag\/wp-content\/uploads\/2024\/08\/comparison-of-boso-and-duolingo-plus-accounts-3-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-25575\" class=\"wp-caption-text\">\u0645\u0642\u0627\u06cc\u0633\u0647 \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648<\/figcaption><\/figure>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D9%82%D8%A7%DB%8C%D8%B3%D9%87_%D8%A8%D9%88%D8%B3%D9%88_%D9%88_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88\"><\/span><span style=\"color: #36bf36;\">\u0645\u0642\u0627\u06cc\u0633\u0647 \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">\u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648. \u0647\u0631 \u06a9\u062f\u0627\u0645 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u0645\u0646\u062d\u0635\u0631 \u0628\u0647 \u0641\u0631\u062f\u06cc \u062f\u0627\u0631\u0646\u062f. \u0628\u0648\u0633\u0648 \u0645\u062b\u0644 \u06cc\u06a9 \u0645\u0639\u0644\u0645 \u0628\u0627\u062a\u062c\u0631\u0628\u0647 \u0639\u0645\u0644 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0645\u062d\u062a\u0648\u0627\u06cc\u0634 \u0628\u0631 \u0627\u0633\u0627\u0633 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627\u06cc \u0627\u0631\u0648\u067e\u0627\u06cc\u06cc \u0627\u0633\u062a \u0648 \u0634\u0645\u0627 \u0631\u0627 \u0628\u0631\u0627\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0632\u0628\u0627\u0646 \u062f\u0631 \u062f\u0646\u06cc\u0627\u06cc \u0648\u0627\u0642\u0639\u06cc \u0622\u0645\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0645\u06a9\u0627\u0644\u0645\u0647 \u062f\u0631 \u0631\u0633\u062a\u0648\u0631\u0627\u0646\u060c \u062e\u0631\u06cc\u062f \u062f\u0631 \u0641\u0631\u0648\u0634\u06af\u0627\u0647 \u06cc\u0627 \u06af\u067e \u0632\u062f\u0646 \u0628\u0627 \u0647\u0645\u06a9\u0627\u0631\u0627\u0646 &#8211; \u0628\u0648\u0633\u0648 \u0634\u0645\u0627 \u0631\u0627 \u0628\u0631\u0627\u06cc \u0647\u0645\u0647 \u0627\u06cc\u0646\u0647\u0627 \u0622\u0645\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f!<\/p>\n<p style=\"text-align: justify;\">\u0627\u0632 \u0637\u0631\u0641 \u062f\u06cc\u06af\u0631\u060c \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u0645\u062b\u0644 \u06cc\u06a9 \u0645\u0639\u0644\u0645 \u062e\u0648\u0634\u200c\u0630\u0648\u0642 \u0627\u0633\u062a \u06a9\u0647 \u0647\u0645\u06cc\u0634\u0647 \u0686\u06cc\u0632 \u062c\u062f\u06cc\u062f\u06cc \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u062f\u0627\u0631\u062f. \u062f\u0627\u0633\u062a\u0627\u0646\u200c\u0647\u0627\u06cc \u062c\u0630\u0627\u0628\u060c \u0645\u0642\u0627\u0644\u0627\u062a \u062e\u0648\u0627\u0646\u062f\u0646\u06cc \u0648 \u067e\u0627\u062f\u06a9\u0633\u062a\u200c\u0647\u0627\u06cc \u06af\u0648\u0634\u200c\u0646\u0648\u0627\u0632 \u06a9\u0647 \u0628\u0627 \u062a\u0646\u0648\u0639 \u0645\u062d\u062a\u0648\u0627\u06cc\u0634 \u062d\u0648\u0635\u0644\u0647\u200c\u062a\u0627\u0646 \u0631\u0627 \u0633\u0631 \u0646\u0645\u06cc\u200c\u0628\u0631\u062f. \u067e\u0633\u060c \u0627\u06af\u0631 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u06cc\u062f \u0632\u0628\u0627\u0646 \u0631\u0627 \u0628\u0631\u0627\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0639\u0645\u0644\u06cc \u06cc\u0627\u062f \u0628\u06af\u06cc\u0631\u06cc\u062f\u060c \u0628\u0648\u0633\u0648 \u06af\u0632\u06cc\u0646\u0647 \u062e\u0648\u0628\u06cc \u0627\u0633\u062a. \u0627\u0645\u0627 \u0627\u06af\u0631 \u062f\u0646\u0628\u0627\u0644 \u062a\u0646\u0648\u0639 \u0648 \u0633\u0631\u06af\u0631\u0645\u06cc \u062f\u0631 \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0647\u0633\u062a\u06cc\u062f\u060c \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0627\u0646\u062a\u062e\u0627\u0628 \u062c\u0630\u0627\u0628\u06cc \u0628\u0627\u0634\u062f.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D9%82%D8%A7%DB%8C%D8%B3%D9%87_%D8%AA%D8%B9%D8%AF%D8%A7%D8%AF_%D8%B2%D8%A8%D8%A7%D9%86_%D9%87%D8%A7%DB%8C_%D8%A8%D9%88%D8%B3%D9%88_%D9%88_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88\"><\/span><span style=\"color: #36bf36;\">\u0645\u0642\u0627\u06cc\u0633\u0647 \u062a\u0639\u062f\u0627\u062f \u0632\u0628\u0627\u0646 \u0647\u0627\u06cc \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0647\u0631 \u062f\u0648 \u067e\u0644\u062a\u0641\u0631\u0645 14 \u0632\u0628\u0627\u0646 \u0645\u0634\u062a\u0631\u06a9 \u062f\u0627\u0631\u0646\u062f\u060c \u0627\u0632 \u062c\u0645\u0644\u0647 \u0627\u0646\u06af\u0644\u06cc\u0633\u06cc\u060c \u0627\u0633\u067e\u0627\u0646\u06cc\u0627\u06cc\u06cc\u060c \u0698\u0627\u067e\u0646\u06cc\u060c \u0641\u0631\u0627\u0646\u0633\u0648\u06cc\u060c \u0622\u0644\u0645\u0627\u0646\u06cc \u0648 \u0686\u06cc\u0646\u06cc (\u0645\u0627\u0646\u062f\u0627\u0631\u06cc\u0646). \u0628\u0648\u0633\u0648 \u0647\u06cc\u0686 \u0632\u0628\u0627\u0646 \u0645\u0646\u062d\u0635\u0631 \u0628\u0647 \u0641\u0631\u062f\u06cc \u0646\u062f\u0627\u0631\u062f \u06a9\u0647 \u062f\u0631 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u0646\u0628\u0627\u0634\u062f. \u0627\u0645\u0627 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 29 \u0632\u0628\u0627\u0646 \u0627\u0636\u0627\u0641\u06cc \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f \u06a9\u0647 \u062f\u0631 \u0628\u0648\u0633\u0648 \u0645\u0648\u062c\u0648\u062f \u0646\u06cc\u0633\u062a\u0646\u062f. \u0627\u06cc\u0646 \u0632\u0628\u0627\u0646\u200c\u0647\u0627 \u0634\u0627\u0645\u0644 \u06a9\u0627\u062a\u0627\u0644\u0627\u0646\u060c \u0686\u06a9\u060c \u062f\u0627\u0646\u0645\u0627\u0631\u06a9\u06cc\u060c \u0627\u0633\u067e\u0631\u0627\u0646\u062a\u0648\u060c \u0641\u0646\u0644\u0627\u0646\u062f\u06cc\u060c \u06cc\u0648\u0646\u0627\u0646\u06cc\u060c \u0647\u0646\u062f\u06cc\u060c \u0627\u0646\u062f\u0648\u0646\u0632\u06cc\u0627\u06cc\u06cc\u060c \u0633\u0648\u0626\u062f\u06cc \u0648 \u062d\u062a\u06cc \u0632\u0628\u0627\u0646\u200c\u0647\u0627\u06cc \u0633\u0627\u062e\u062a\u06af\u06cc \u0645\u0627\u0646\u0646\u062f \u06a9\u0644\u06cc\u0646\u06af\u0648\u0646 \u0648 \u0648\u0627\u0644\u0631\u06cc\u0627\u0646 \u0645\u06cc \u0628\u0627\u0634\u062f.<\/p>\n<p style=\"text-align: justify;\">\u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u062a\u0646\u0648\u0639 \u0628\u0633\u06cc\u0627\u0631 \u0628\u06cc\u0634\u062a\u0631\u06cc \u0627\u0632 \u0632\u0628\u0627\u0646\u200c\u0647\u0627 \u0631\u0627 \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f \u0627\u0645\u0627 \u0628\u0648\u0633\u0648 \u0628\u0631 \u0632\u0628\u0627\u0646\u200c\u0647\u0627\u06cc \u067e\u0631\u06a9\u0627\u0631\u0628\u0631\u062f \u0648 \u0631\u0627\u06cc\u062c \u062a\u0645\u0631\u06a9\u0632 \u062f\u0627\u0631\u062f. \u0628\u0631\u0627\u06cc \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0632\u0628\u0627\u0646\u200c\u0647\u0627\u06cc \u0627\u0635\u0644\u06cc\u060c \u0647\u0631 \u062f\u0648 \u067e\u0644\u062a\u0641\u0631\u0645 \u0645\u0646\u0627\u0633\u0628 \u0647\u0633\u062a\u0646\u062f\u060c \u0627\u0645\u0627 \u0628\u0631\u0627\u06cc \u062a\u0646\u0648\u0639 \u0628\u06cc\u0634\u062a\u0631 \u06cc\u0627 \u0632\u0628\u0627\u0646\u200c\u0647\u0627\u06cc \u062e\u0627\u0635\u060c \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u0627\u0646\u062a\u062e\u0627\u0628 \u0628\u0647\u062a\u0631\u06cc \u0627\u0633\u062a.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D9%82%D8%A7%DB%8C%D8%B3%D9%87_%D8%B1%D9%88%D8%B4_%D8%AA%D8%AF%D8%B1%DB%8C%D8%B3_%D8%A8%D9%88%D8%B3%D9%88_%D9%88_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88\"><\/span><span style=\"color: #36bf36;\">\u0645\u0642\u0627\u06cc\u0633\u0647 \u0631\u0648\u0634 \u062a\u062f\u0631\u06cc\u0633 \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0628\u0648\u0633\u0648 \u0645\u0627\u0646\u0646\u062f \u06cc\u06a9 \u0645\u0639\u0644\u0645 \u062f\u0642\u06cc\u0642 \u0648 \u0645\u0646\u0638\u0645 \u0639\u0645\u0644 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0645\u0639\u0644\u0645 \u0634\u0645\u0627 \u0631\u0627 \u0642\u062f\u0645 \u0628\u0647 \u0642\u062f\u0645 \u0628\u0627 \u0642\u0648\u0627\u0639\u062f \u062f\u0633\u062a\u0648\u0631\u06cc \u0648 \u0644\u063a\u0627\u062a \u062c\u062f\u06cc\u062f \u0622\u0634\u0646\u0627 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0645\u0627\u0646\u0646\u062f \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u062f\u0631 \u06a9\u0644\u0627\u0633\u06cc \u0646\u0634\u0633\u062a\u0647\u200c\u0627\u06cc\u062f \u06a9\u0647 \u0645\u0639\u0644\u0645 \u0628\u0627 \u062d\u0648\u0635\u0644\u0647 \u0647\u0631 \u0628\u062e\u0634 \u0631\u0627 \u062c\u062f\u0627\u06af\u0627\u0646\u0647 \u062a\u0648\u0636\u06cc\u062d \u0645\u06cc\u200c\u062f\u0647\u062f.<\/p>\n<p style=\"text-align: justify;\">\u062f\u0631 \u0645\u0642\u0627\u0628\u0644\u060c \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u0634\u0645\u0627 \u0631\u0627 \u0628\u0647 \u062f\u0644 \u0645\u0627\u062c\u0631\u0627 \u0645\u06cc\u200c\u0628\u0631\u062f! \u0627\u06cc\u0646 \u0645\u0639\u0644\u0645 \u0634\u0645\u0627 \u0631\u0627 \u062f\u0631 \u0645\u062d\u06cc\u0637 \u0648\u0627\u0642\u0639\u06cc \u063a\u0648\u0637\u0647\u200c\u0648\u0631 \u0645\u06cc \u0633\u0627\u0632\u062f \u0648 \u0632\u0628\u0627\u0646 \u0631\u0627 \u0627\u0632 \u0637\u0631\u06cc\u0642 \u062a\u0639\u0627\u0645\u0644 \u0628\u0627 \u0645\u062a\u0646\u200c\u0647\u0627\u060c \u0645\u06a9\u0627\u0644\u0645\u0627\u062a \u0648 \u062f\u0627\u0633\u062a\u0627\u0646\u200c\u0647\u0627\u06cc \u062c\u0630\u0627\u0628 \u0622\u0645\u0648\u0632\u0634 \u0645\u06cc \u062f\u0647\u062f. \u0647\u0631 \u062f\u0648 \u0631\u0648\u0634 \u0645\u0632\u0627\u06cc\u0627\u06cc \u062e\u0648\u062f \u0631\u0627 \u062f\u0627\u0631\u0646\u062f. \u0628\u0648\u0633\u0648 \u0628\u0631\u0627\u06cc \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u0628\u0647 \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0633\u0627\u062e\u062a\u0627\u0631\u0645\u0646\u062f \u0639\u0644\u0627\u0642\u0647 \u062f\u0627\u0631\u0646\u062f \u0645\u0646\u0627\u0633\u0628 \u0627\u0633\u062a\u060c \u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u0628\u0631\u0627\u06cc \u06a9\u0633\u0627\u0646\u06cc \u06a9\u0647 \u0627\u0632 \u062a\u062c\u0631\u0628\u0647\u200c\u0647\u0627\u06cc \u0639\u0645\u0644\u06cc \u0644\u0630\u062a \u0645\u06cc\u200c\u0628\u0631\u0646\u062f\u060c \u06af\u0632\u06cc\u0646\u0647\u200c\u0627\u06cc \u0639\u0627\u0644\u06cc \u0645\u062d\u0633\u0648\u0628 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D9%82%D8%A7%DB%8C%D8%B3%D9%87_%D9%88%D8%A7%DA%98%DA%AF%D8%A7%D9%86_%D8%A8%D9%88%D8%B3%D9%88_%D9%88_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88\"><\/span><span style=\"color: #36bf36;\">\u0645\u0642\u0627\u06cc\u0633\u0647 \u0648\u0627\u0698\u06af\u0627\u0646 \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u0628\u0627 \u062a\u0645\u0631\u06a9\u0632 \u0628\u0631 \u062a\u0646\u0648\u0639 \u0648\u0627\u0698\u06af\u0627\u0646\u060c \u06af\u0646\u062c\u06cc\u0646\u0647\u200c\u0627\u06cc \u0627\u0632 \u06a9\u0644\u0645\u0627\u062a \u0631\u0627 \u067e\u06cc\u0634 \u0631\u0648\u06cc \u0634\u0645\u0627 \u0645\u06cc\u200c\u06af\u0630\u0627\u0631\u062f. \u0627\u0645\u0627 \u06af\u0627\u0647\u06cc \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062f\u0631 \u06a9\u0627\u0631\u0628\u0631\u062f \u0635\u062d\u06cc\u062d \u0627\u06cc\u0646 \u06a9\u0644\u0645\u0627\u062a \u062e\u0648\u0628 \u0639\u0645\u0644 \u0646\u06a9\u0646\u062f. \u0627\u0632 \u0637\u0631\u0641 \u062f\u06cc\u06af\u0631\u060c \u0628\u0648\u0633\u0648 \u0628\u0627 \u0631\u0648\u06cc\u06a9\u0631\u062f\u06cc \u0639\u0645\u06cc\u0642\u200c\u062a\u0631\u060c \u0634\u0645\u0627 \u0631\u0627 \u0628\u0627 \u062a\u0639\u062f\u0627\u062f \u06a9\u0645\u062a\u0631\u06cc \u0648\u0627\u0698\u0647 \u0622\u0634\u0646\u0627 \u0645\u06cc\u200c\u06a9\u0646\u062f\u060c \u0627\u0645\u0627 \u06cc\u0627\u062f \u0645\u06cc\u200c\u062f\u0647\u062f \u0686\u0637\u0648\u0631 \u0627\u0632 \u0622\u0646\u200c\u0647\u0627 \u062f\u0631\u0633\u062a \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f. \u0627\u06cc\u0646 \u0628\u0631\u0646\u0627\u0645\u0647 \u0628\u0627 \u067e\u06cc\u0631\u0648\u06cc \u0627\u0632 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f CEFR\u060c \u0645\u0633\u06cc\u0631\u06cc \u0645\u0646\u0638\u0645 \u0628\u0631\u0627\u06cc \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u062a\u0631\u0633\u06cc\u0645 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0628\u0648\u0633\u0648 \u0628\u0627 \u062a\u0631\u06a9\u06cc\u0628\u06cc \u0627\u0632 \u062a\u0645\u0631\u06cc\u0646\u200c\u0647\u0627\u06cc \u062e\u0648\u0627\u0646\u062f\u0646\u060c \u0634\u0646\u06cc\u062f\u0646 \u0648 \u0646\u0648\u0634\u062a\u0646\u060c \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f \u062a\u0627 \u0648\u0627\u0698\u06af\u0627\u0646 \u0631\u0627 \u0628\u0647\u062a\u0631 \u0628\u0647 \u062e\u0627\u0637\u0631 \u0628\u0633\u067e\u0627\u0631\u06cc\u062f.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D9%82%D8%A7%DB%8C%D8%B3%D9%87_%DA%AF%D8%B1%D8%A7%D9%85%D8%B1_%D8%A8%D9%88%D8%B3%D9%88_%D9%88_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88\"><\/span><span style=\"color: #36bf36;\">\u0645\u0642\u0627\u06cc\u0633\u0647 \u06af\u0631\u0627\u0645\u0631 \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0628\u0648\u0633\u0648 \u0645\u062b\u0644 \u06cc\u06a9 \u0645\u0639\u0644\u0645 \u062f\u0644\u0633\u0648\u0632 \u0642\u0648\u0627\u0639\u062f \u06af\u0631\u0627\u0645\u0631\u06cc \u0631\u0627 \u0633\u0627\u062f\u0647 \u0648 \u062f\u0642\u06cc\u0642 \u062a\u0648\u0636\u06cc\u062d \u0645\u06cc\u200c\u062f\u0647\u062f. \u062c\u0645\u0644\u0647\u200c\u0647\u0627\u06cc \u0648\u0627\u0642\u0639\u06cc \u0648 \u067e\u06cc\u0686\u06cc\u062f\u0647\u200c\u062a\u0631 \u0631\u0627 \u0628\u0647 \u06a9\u0627\u0631 \u0645\u06cc\u200c\u0628\u0631\u062f \u062a\u0627 \u0634\u0645\u0627 \u0628\u062a\u0648\u0627\u0646\u06cc\u062f \u0632\u0628\u0627\u0646 \u0631\u0627 \u062f\u0631 \u062f\u0646\u06cc\u0627\u06cc \u0648\u0627\u0642\u0639\u06cc \u0628\u0647 \u06a9\u0627\u0631 \u0628\u0628\u0631\u06cc\u062f. \u0627\u0645\u0627 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u0645\u0639\u0644\u0645 \u0645\u062a\u0641\u0627\u0648\u062a\u06cc \u0627\u0633\u062a. \u062f\u0631 \u062a\u0648\u0636\u06cc\u062d \u06af\u0631\u0627\u0645\u0631\u060c \u0633\u0639\u06cc \u0645\u06cc \u06a9\u0646\u062f \u0622\u0646 \u0631\u0627 \u062f\u0631 \u0642\u0627\u0644\u0628 \u0628\u0627\u0632\u06cc \u0647\u0627 \u0648 \u0645\u06a9\u0627\u0644\u0645\u0627\u062a \u062c\u0630\u0627\u0628 \u0628\u0647 \u0634\u0645\u0627 \u0628\u06cc\u0627\u0645\u0648\u0632\u062f.<\/p>\n<p style=\"text-align: justify;\">\u062f\u0631 \u0645\u062c\u0645\u0648\u0639 \u0627\u06af\u0631 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u06cc\u062f \u0633\u0631\u06cc\u0639 \u062f\u0627\u06cc\u0631\u0647 \u0644\u063a\u0627\u062a \u062e\u0648\u062f \u0631\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0647\u06cc\u062f \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u062e\u0648\u0628 \u0627\u0633\u062a. \u0627\u0645\u0627 \u0627\u06af\u0631 \u062f\u0646\u0628\u0627\u0644 \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0639\u0645\u06cc\u0642\u200c\u062a\u0631 \u0647\u0633\u062a\u06cc\u062f\u060c \u06cc\u0639\u0646\u06cc \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u06cc\u062f \u06a9\u0644\u0645\u0627\u062a \u0631\u0627 \u062f\u0631\u0633\u062a\u060c \u062f\u0631 \u0645\u0648\u0642\u0639\u06cc\u062a\u200c\u0647\u0627\u06cc \u0648\u0627\u0642\u0639\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f \u0648 \u06af\u0631\u0627\u0645\u0631 \u0631\u0627 \u062e\u0648\u0628 \u06cc\u0627\u062f \u0628\u06af\u06cc\u0631\u06cc\u062f\u060c \u0628\u0648\u0633\u0648 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0645\u0639\u0644\u0645 \u0628\u0647\u062a\u0631\u06cc \u0628\u0627\u0634\u062f.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D9%82%D8%A7%DB%8C%D8%B3%D9%87_%D9%86%D9%88%D8%B4%D8%AA%D8%A7%D8%B1%DB%8C_%D8%A8%D9%88%D8%B3%D9%88_%D8%A8%D8%A7_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88\"><\/span><span style=\"color: #36bf36;\">\u0645\u0642\u0627\u06cc\u0633\u0647 \u0646\u0648\u0634\u062a\u0627\u0631\u06cc \u0628\u0648\u0633\u0648 \u0628\u0627 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u062a\u0635\u0648\u0631 \u06a9\u0646\u06cc\u062f \u0628\u0631\u0627\u06cc \u0631\u0626\u06cc\u0633\u200c\u062a\u0627\u0646 \u0645\u06cc \u062e\u0648\u0627\u0647\u06cc\u062f \u0646\u0627\u0645\u0647 \u0628\u0646\u0648\u06cc\u0633\u06cc\u062f. \u0628\u0648\u0633\u0648 \u0628\u0647 \u0634\u0645\u0627 \u06cc\u0627\u062f \u0645\u06cc\u200c\u062f\u0647\u062f \u06a9\u062f\u0627\u0645 \u06a9\u0644\u0645\u0627\u062a \u0648 \u062c\u0645\u0644\u0647\u200c\u0647\u0627 \u0628\u0631\u0627\u06cc \u0647\u0631 \u0645\u0648\u0642\u0639\u06cc\u062a \u0645\u0646\u0627\u0633\u0628\u200c\u062a\u0631\u0646\u062f. \u0628\u0648\u0633\u0648\u060c \u062a\u0648\u0636\u06cc\u062d \u0645\u06cc\u200c\u062f\u0647\u062f \u0686\u0631\u0627 \u0648 \u0686\u0637\u0648\u0631 \u0627\u0632 \u0647\u0631 \u0639\u0628\u0627\u0631\u062a \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u0645. \u0628\u0627 \u0628\u0648\u0633\u0648\u060c \u0634\u0645\u0627 \u0641\u0642\u0637 \u06a9\u0644\u0645\u0647 \u062d\u0641\u0638 \u0646\u0645\u06cc\u200c\u06a9\u0646\u06cc\u062f\u060c \u0628\u0644\u06a9\u0647 \u06cc\u0627\u062f \u0645\u06cc\u200c\u06af\u06cc\u0631\u06cc\u062f \u0686\u0637\u0648\u0631 \u062f\u0631 \u062f\u0646\u06cc\u0627\u06cc \u0648\u0627\u0642\u0639\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f \u0648 \u0628\u0646\u0648\u06cc\u0633\u06cc\u062f. \u0627\u0646\u06af\u0627\u0631 \u06a9\u0647 \u062f\u0627\u0631\u06cc\u062f \u0632\u0628\u0627\u0646 \u0631\u0627 \u062f\u0631 \u06a9\u0634\u0648\u0631\u06cc \u06a9\u0647 \u0628\u0647 \u0622\u0646 \u0632\u0628\u0627\u0646 \u0635\u062d\u0628\u062a \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u060c \u06cc\u0627\u062f \u0645\u06cc\u200c\u06af\u06cc\u0631\u06cc\u062f!<\/p>\n<p style=\"text-align: justify;\">\u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u0646\u06cc\u0632 \u062f\u0631 \u0627\u06cc\u0646 \u0632\u0645\u06cc\u0646\u0647 \u0646\u0648\u0634\u062a\u0627\u0631 \u0648 \u062c\u0645\u0644\u0647 \u0633\u0627\u0632\u06cc \u0628\u0633\u06cc\u0627\u0631 \u062e\u0648\u0628 \u0639\u0645\u0644 \u0645\u06cc \u06a9\u0646\u062f\u060c \u0627\u0645\u0627 \u0622\u0646\u0647\u0627 \u0631\u0627 \u062f\u0631 \u0642\u0627\u0644\u0628 \u0628\u0627\u0632\u06cc \u0628\u0647 \u0634\u0645\u0627 \u06cc\u0627\u062f \u0645\u06cc \u062f\u0647\u062f \u06a9\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0634\u0645\u0627 \u0628\u0647 \u062e\u0648\u0628\u06cc \u0646\u062a\u0648\u0627\u0646\u06cc\u062f \u06a9\u0627\u0631\u0628\u0631\u062f \u0622\u0646\u0647\u0627 \u0631\u0627 \u062f\u0631 \u0646\u0648\u0634\u062a\u0646 \u06cc\u06a9 \u0646\u0627\u0645\u0647 \u0628\u0647 \u0631\u0626\u06cc\u0633\u200c\u062a\u0627\u0646 \u0628\u0647 \u062e\u0648\u0628\u06cc \u0628\u0647 \u06a9\u0627\u0631 \u0628\u0628\u0631\u06cc\u062f.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D9%82%D8%A7%DB%8C%D8%B3%D9%87_%D8%AF%D8%B1%DA%A9_%D9%85%D8%B7%D9%84%D8%A8_%D8%A8%D9%88%D8%B3%D9%88_%D9%88_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88\"><\/span><span style=\"color: #36bf36;\">\u0645\u0642\u0627\u06cc\u0633\u0647 \u062f\u0631\u06a9 \u0645\u0637\u0644\u0628 \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u0647\u0631 \u062f\u0648\u060c \u0631\u0627\u0647\u200c\u0647\u0627\u06cc \u0633\u0631\u06af\u0631\u0645\u200c\u06a9\u0646\u0646\u062f\u0647\u200c\u0627\u06cc \u0628\u0631\u0627\u06cc \u062a\u0642\u0648\u06cc\u062a \u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u062e\u0648\u0627\u0646\u062f\u0646 \u0648 \u0634\u0646\u06cc\u062f\u0646 \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f. \u062a\u0635\u0648\u0631 \u06a9\u0646\u06cc\u062f \u062f\u0627\u0631\u06cc\u062f \u062f\u0627\u0633\u062a\u0627\u0646\u200c\u0647\u0627\u06cc \u06a9\u0648\u062a\u0627\u0647 \u0648 \u062c\u0630\u0627\u0628 \u0645\u06cc\u200c\u062e\u0648\u0627\u0646\u06cc\u062f \u0648 \u0628\u0647 \u0633\u0648\u0627\u0644\u200c\u0647\u0627\u06cc \u0645\u0631\u062a\u0628\u0637 \u062c\u0648\u0627\u0628 \u0645\u06cc\u062f\u0647\u06cc\u062f. \u0627\u06cc\u0646 \u0647\u0645\u0648\u0646 \u06a9\u0627\u0631\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u0628\u0627 \u062f\u0627\u0633\u062a\u0627\u0646\u200c\u0647\u0627\u06cc\u0634 \u0627\u0646\u062c\u0627\u0645 \u0645\u06cc\u062f\u0647\u062f. \u062f\u0631 \u0645\u0642\u0627\u0628\u0644 \u0628\u0648\u0633\u0648. \u0634\u0645\u0627 \u0631\u0627 \u0628\u0647 \u0645\u0648\u0642\u0639\u06cc\u062a\u200c\u0647\u0627\u06cc \u0648\u0627\u0642\u0639\u06cc \u0632\u0646\u062f\u06af\u06cc \u0645\u06cc\u200c\u0628\u0631\u062f. \u0645\u062b\u0644\u0627\u064b\u060c \u062a\u0635\u0648\u0631 \u06a9\u0646\u06cc\u062f \u0645\u06cc \u062e\u0648\u0627\u0647\u06cc\u062f \u0628\u0644\u06cc\u0637 \u0642\u0637\u0627\u0631 \u0628\u062e\u0631\u06cc\u062f \u0648 \u06cc\u0627 \u067e\u0631\u0648\u0627\u0632 \u0631\u0632\u0631\u0648 \u06a9\u0646\u06cc\u062f\u060c \u06cc\u0627 \u0627\u0632 \u06cc\u06a9 \u062c\u0627\u06cc \u062f\u06cc\u062f\u0646\u06cc \u0628\u0627\u0632\u062f\u06cc\u062f \u06a9\u0646\u06cc\u062f. \u0628\u0648\u0633\u0648 \u0628\u0627 \u062a\u0645\u0631\u06cc\u0646\u0627\u062a \u0645\u0631\u062a\u0628\u0637\u060c \u0627\u06cc\u0646 \u062a\u062c\u0631\u0628\u0647\u200c\u0647\u0627 \u0631\u0627 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0634\u0628\u06cc\u0647\u200c\u0633\u0627\u0632\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D9%82%D8%A7%DB%8C%D8%B3%D9%87_%D9%85%DA%A9%D8%A7%D9%84%D9%85%D9%87_%D8%A8%D9%88%D8%B3%D9%88_%D9%88_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88\"><\/span><span style=\"color: #36bf36;\">\u0645\u0642\u0627\u06cc\u0633\u0647 \u0645\u06a9\u0627\u0644\u0645\u0647 \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u0628\u0627 \u062a\u0645\u0631\u06cc\u0646\u0627\u062a \u062a\u0644\u0641\u0638 \u062e\u0648\u0628\u0634 \u06cc\u06a9\u06cc \u0627\u0632 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0646\u0631\u0645 \u0627\u0641\u0632\u0627\u0631 \u0647\u0627 \u0628\u0631\u0627\u06cc \u0627\u0631\u062a\u0642\u0627\u06cc \u0645\u0647\u0627\u0631\u062a \u0647\u0627\u06cc \u06af\u0641\u062a\u0627\u0631\u06cc \u0627\u0633\u062a. \u0627\u0645\u0627 \u06af\u0627\u0647\u06cc \u0627\u0648\u0642\u0627\u062a \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0635\u062f\u0627\u06cc \u0631\u0628\u0627\u062a\u06cc\u06a9\u0634 \u0622\u0632\u0627\u0631\u062f\u0647\u0646\u062f\u0647 \u0628\u0627\u0634\u062f. \u0627\u0645\u0627 \u0628\u0648\u0633\u0648\u060c \u0634\u0645\u0627 \u0631\u0648 \u0628\u0627 \u0627\u0641\u0631\u0627\u062f \u0628\u0648\u0645\u06cc \u0622\u0634\u0646\u0627 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0628\u0627 \u0628\u0648\u0633\u0648 \u0634\u0645\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0627 \u06a9\u0633\u06cc \u06a9\u0647 \u0632\u0628\u0627\u0646 \u0645\u0627\u062f\u0631\u06cc \u0648 \u0628\u0648\u0645\u06cc\u0634 \u0627\u0633\u062a \u062d\u0631\u0641 \u0628\u0632\u0646\u06cc\u062f \u0648 \u0646\u0648\u0634\u062a\u0646 \u0631\u0648 \u062a\u0645\u0631\u06cc\u0646 \u06a9\u0646\u06cc\u062f. \u0628\u0639\u062f \u0627\u0632 \u0647\u0631 \u062f\u0631\u0633\u060c \u06cc\u0647 \u0645\u0648\u0636\u0648\u0639 \u062c\u0627\u0644\u0628 \u0628\u0631\u0627\u06cc \u0635\u062d\u0628\u062a \u062f\u0627\u0631\u06cc\u062f \u0648 \u0645\u06cc\u200c\u062a\u0648\u0646\u06cc\u062f \u0646\u0638\u0631 \u06cc\u0647 \u0641\u0631\u062f \u0628\u0648\u0645\u06cc \u0631\u0648 \u062f\u0631 \u0645\u0648\u0631\u062f \u0622\u0646 \u0628\u067e\u0631\u0633\u06cc\u062f.<\/p>\n<p style=\"text-align: justify;\">\u062f\u0631 \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0632\u0628\u0627\u0646 \u0628\u0647 \u06cc\u0627\u062f \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u06a9\u0647 \u0647\u06cc\u0686 \u0686\u06cc\u0632 \u062c\u0627\u06cc \u062a\u0645\u0631\u06cc\u0646 \u0635\u062d\u0628\u062a \u06a9\u0631\u062f\u0646 \u0631\u0648 \u0646\u0645\u06cc\u200c\u06af\u06cc\u0631\u062f. \u067e\u0633 \u0627\u06cc\u0646 \u0627\u0645\u0631 \u0631\u0627 \u062c\u062f\u06cc \u0628\u06af\u06cc\u0631\u06cc\u062f \u0648 \u062e\u062c\u0627\u0644\u062a \u0631\u0648 \u0628\u0630\u0627\u0631\u06cc\u062f \u06a9\u0646\u0627\u0631 \u0648 \u0634\u0631\u0648\u0639 \u06a9\u0646\u06cc\u062f \u0628\u0647 \u062d\u0631\u0641 \u0632\u062f\u0646.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%DA%AF%D9%88%D8%A7%D9%87%DB%8C_CEFR_%D8%A8%D9%88%D8%B3%D9%88_%D9%88_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88\"><\/span><span style=\"color: #36bf36;\">\u06af\u0648\u0627\u0647\u06cc CEFR \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u062f\u0648\u0631\u0647\u200c\u0647\u0627\u06cc \u0628\u0648\u0633\u0648 \u0628\u0631 \u0627\u0633\u0627\u0633 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc CEFR \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0647\u200c\u0627\u0646\u062f. \u0627\u06cc\u0646 \u06cc\u0639\u0646\u06cc \u0634\u0645\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0633\u0637\u062d \u0632\u0628\u0627\u0646 \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u0637\u0648\u0631 \u062f\u0642\u06cc\u0642 \u0627\u0646\u062f\u0627\u0632\u0647\u200c\u06af\u06cc\u0631\u06cc \u06a9\u0646\u06cc\u062f \u0648 \u062d\u062a\u06cc \u06af\u0648\u0627\u0647\u06cc \u0631\u0633\u0645\u06cc \u062f\u0631\u06cc\u0627\u0641\u062a \u06a9\u0646\u06cc\u062f! \u0627\u0632 \u0637\u0631\u0641 \u062f\u06cc\u06af\u0631\u060c \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u0628\u0631\u0627\u06cc \u06a9\u0633\u0627\u0646\u06cc \u0645\u0646\u0627\u0633\u0628 \u0627\u0633\u062a \u06a9\u0647 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u0646\u062f \u0628\u0647 \u0634\u06a9\u0644\u06cc \u0633\u0631\u06af\u0631\u0645\u200c\u06a9\u0646\u0646\u062f\u0647 \u0648 \u0628\u062f\u0648\u0646 \u0641\u0634\u0627\u0631 \u0632\u0628\u0627\u0646 \u06cc\u0627\u062f \u0628\u06af\u06cc\u0631\u0646\u062f. \u0627\u06af\u0631\u0686\u0647 \u062f\u0648\u0631\u0647\u200c\u0647\u0627\u06cc \u0622\u0646 \u0628\u0631 \u0627\u0633\u0627\u0633 CEFR \u0646\u06cc\u0633\u062a\u060c \u0627\u0645\u0627 \u0631\u0648\u0634\u06cc \u062c\u0630\u0627\u0628 \u0648 \u0645\u0641\u0631\u062d \u0628\u0631\u0627\u06cc \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f. \u067e\u0633\u060c \u0627\u06af\u0631 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0631\u0633\u0645\u06cc \u0648 \u062f\u0631\u06cc\u0627\u0641\u062a \u06af\u0648\u0627\u0647\u06cc \u0647\u0633\u062a\u06cc\u062f\u060c \u0628\u0648\u0633\u0648 \u0627\u0646\u062a\u062e\u0627\u0628 \u0628\u0647\u062a\u0631\u06cc \u0627\u0633\u062a.<\/p>\n<h4 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%DA%AF%D9%88%D8%A7%D9%87%DB%8C_%D8%B2%D8%A8%D8%A7%D9%86_CEFR_%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\"><\/span><span style=\"color: #36bf36;\">\u06af\u0648\u0627\u0647\u06cc \u0632\u0628\u0627\u0646 CEFR \u0686\u06cc\u0633\u062a\u061f<\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p style=\"text-align: justify;\">CEFR \u0628\u0647 \u0634\u0645\u0627 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u06cc \u0622\u0645\u0648\u0632\u0634\u06cc \u0645\u0646\u0627\u0633\u0628 \u062e\u0648\u062f\u062a\u0627\u0646 \u0631\u0627 \u067e\u06cc\u062f\u0627 \u06a9\u0646\u06cc\u062f. \u0648\u0642\u062a\u06cc \u0645\u06cc\u200c\u062f\u0627\u0646\u06cc\u062f \u062f\u0631 \u0686\u0647 \u0633\u0637\u062d\u06cc \u0647\u0633\u062a\u06cc\u062f\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u062f\u0648\u0631\u0647\u200c\u0627\u06cc \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0646\u0647 \u062e\u06cc\u0644\u06cc \u0633\u0627\u062f\u0647 \u0627\u0633\u062a \u0648 \u0646\u0647 \u062e\u06cc\u0644\u06cc \u0633\u062e\u062a. \u067e\u0633\u060c \u0648\u0642\u062a\u06cc \u062f\u0646\u0628\u0627\u0644 \u06cc\u06a9 \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u06cc \u0632\u0628\u0627\u0646 \u0645\u06cc\u200c\u06af\u0631\u062f\u06cc\u062f\u060c \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u0622\u0646\u0647\u0627\u06cc\u06cc \u0628\u0627\u0634\u06cc\u062f \u06a9\u0647 \u0627\u0632 CEFR \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0627\u06cc\u0646 \u0637\u0648\u0631\u06cc \u0645\u0637\u0645\u0626\u0646 \u0645\u06cc\u200c\u0634\u0648\u06cc\u062f \u06a9\u0647 \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0634\u0645\u0627 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0648 \u0645\u0648\u062b\u0631 \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f.<\/p>\n<p style=\"text-align: justify;\">CEFR \u0634\u0634 \u0633\u0637\u062d \u062f\u0627\u0631\u062f\u060c \u0627\u0632 A1 \u06a9\u0647 \u0645\u0628\u062a\u062f\u06cc \u0627\u0633\u062a \u062a\u0627 C2 \u06a9\u0647 \u062a\u0633\u0644\u0637 \u06a9\u0627\u0645\u0644 \u0631\u0627 \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f. \u0645\u062b\u0644 \u067e\u0644\u0647\u200c\u0647\u0627\u06cc \u06cc\u06a9 \u0646\u0631\u062f\u0628\u0627\u0646\u060c \u0647\u0631 \u0633\u0637\u062d \u0634\u0645\u0627 \u0631\u0627 \u0628\u0627\u0644\u0627\u062a\u0631 \u0645\u06cc\u200c\u0628\u0631\u062f. A2 \u06cc\u0639\u0646\u06cc \u0634\u0645\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u06af\u0641\u062a\u06af\u0648\u0647\u0627\u06cc \u0633\u0627\u062f\u0647 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f. B1 \u0648 B2 \u0633\u0637\u0648\u062d \u0645\u062a\u0648\u0633\u0637 \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u062f\u0631 \u0622\u0646\u0647\u0627 \u0631\u0627\u062d\u062a\u200c\u062a\u0631 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0635\u062d\u0628\u062a \u200c\u06a9\u0646\u06cc\u062f. C1 \u0646\u06cc\u0632 \u06cc\u0639\u0646\u06cc \u0634\u0645\u0627 \u062a\u0642\u0631\u06cc\u0628\u0627\u064b \u0645\u062b\u0644 \u06cc\u06a9 \u0628\u0648\u0645\u06cc \u0632\u0628\u0627\u0646 \u0635\u062d\u0628\u062a \u0645\u06cc\u200c\u06a9\u0646\u06cc\u062f.<\/p>\n<h4 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%A7%D9%87%D9%85%DB%8C%D8%AA_%DA%AF%D9%88%D8%A7%D9%87%DB%8C_CEFR\"><\/span><span style=\"color: #36bf36;\">\u0627\u0647\u0645\u06cc\u062a \u06af\u0648\u0627\u0647\u06cc CEFR<\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p style=\"text-align: justify;\">\u0647\u0646\u06af\u0627\u0645 \u0645\u0647\u0627\u062c\u0631\u062a \u06a9\u0627\u0631\u06cc\u060c \u06a9\u0627\u0631\u0641\u0631\u0645\u0627 \u0646\u06af\u0627\u0647\u06cc \u0628\u0647 \u0631\u0632\u0648\u0645\u0647\u200c\u062a\u0627\u0646 \u0645\u06cc\u200c\u0627\u0646\u062f\u0627\u0632\u062f \u0648 \u0686\u0634\u0645\u0627\u0646\u0634 \u0631\u0648\u06cc \u06af\u0648\u0627\u0647\u06cc CEFR \u0634\u0645\u0627 \u0645\u06cc \u0627\u0641\u062a\u062f. \u0627\u06cc\u0646 \u06af\u0648\u0627\u0647\u06cc \u0645\u0639\u062a\u0628\u0631\u060c \u0645\u0647\u0627\u0631\u062a \u0632\u0628\u0627\u0646\u06cc \u0634\u0645\u0627 \u0631\u0627 \u062a\u0623\u06cc\u06cc\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f \u0648 \u0634\u0627\u0646\u0633 \u0627\u0633\u062a\u062e\u062f\u0627\u0645\u200c\u062a\u0627\u0646 \u0631\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u06cc\u200c\u062f\u0647\u062f.<\/p>\n<p style=\"text-align: justify;\">\u0627\u0645\u0627 \u0627\u06cc\u0646 \u0647\u0645\u0647 \u0645\u0627\u062c\u0631\u0627 \u0646\u06cc\u0633\u062a! \u0627\u06af\u0631 \u0631\u0624\u06cc\u0627\u06cc \u062a\u062d\u0635\u06cc\u0644 \u062f\u0631 \u062e\u0627\u0631\u062c \u0631\u0627 \u062f\u0627\u0631\u06cc\u062f\u060c CEFR \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u06a9\u0644\u06cc\u062f \u0648\u0631\u0648\u062f \u0634\u0645\u0627 \u0628\u0647 \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u0645\u0639\u062a\u0628\u0631 \u062c\u0647\u0627\u0646 \u0628\u0627\u0634\u062f. \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0645\u0624\u0633\u0633\u0627\u062a \u0622\u0645\u0648\u0632\u0634\u06cc\u060c \u0627\u06cc\u0646 \u06af\u0648\u0627\u0647\u06cc \u0631\u0627 \u0645\u0639\u06cc\u0627\u0631 \u0633\u0646\u062c\u0634 \u0632\u0628\u0627\u0646 \u0645\u062a\u0642\u0627\u0636\u06cc\u0627\u0646 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f.<\/p>\n<p style=\"text-align: justify;\">\u0627\u06af\u0631 \u0628\u0647 \u0641\u06a9\u0631 \u0645\u0647\u0627\u062c\u0631\u062a \u0647\u0633\u062a\u06cc\u062f\u060c CEFR \u062f\u0631 \u0641\u0631\u0622\u06cc\u0646\u062f \u0627\u062e\u0630 \u0648\u06cc\u0632\u0627 \u0646\u06cc\u0632 \u0646\u0642\u0634 \u0645\u0647\u0645\u06cc \u0627\u06cc\u0641\u0627 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0628\u0631\u062e\u06cc \u06a9\u0634\u0648\u0631\u0647\u0627 \u0628\u0631\u0627\u06cc \u0635\u062f\u0648\u0631 \u0648\u06cc\u0632\u0627\u06cc \u062a\u062d\u0635\u06cc\u0644\u06cc \u06cc\u0627 \u06a9\u0627\u0631\u06cc\u060c \u0633\u0637\u062d \u0645\u0634\u062e\u0635\u06cc \u0627\u0632 \u0627\u06cc\u0646 \u06af\u0648\u0627\u0647\u06cc \u0631\u0627 \u062f\u0631\u062e\u0648\u0627\u0633\u062a \u0645\u06cc \u06a9\u0646\u0646\u062f.<\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%B3%D9%88%D8%A7%D9%84%D8%A7%D8%AA_%D9%85%D8%AA%D8%AF%D8%A7%D9%88%D9%84\"><\/span><span style=\"color: #36bf36;\">\u0633\u0648\u0627\u0644\u0627\u062a \u0645\u062a\u062f\u0627\u0648\u0644<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%A8%D9%88%D8%B3%D9%88_%D8%A8%D8%B1%D8%A7%DB%8C_%D9%85%D8%A8%D8%AA%D8%AF%DB%8C%D8%A7%D9%86_%D8%A8%D9%87%D8%AA%D8%B1_%D8%A7%D8%B3%D8%AA_%DB%8C%D8%A7_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88%D8%9F\"><\/span><span style=\"color: #36bf36;\">\u0628\u0648\u0633\u0648 \u0628\u0631\u0627\u06cc \u0645\u0628\u062a\u062f\u06cc\u0627\u0646 \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u06cc\u0627 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648\u061f<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0647\u0631 \u062f\u0648 \u067e\u0644\u062a\u0641\u0631\u0645 \u0628\u0631\u0627\u06cc \u0645\u0628\u062a\u062f\u06cc\u0627\u0646 \u0645\u0646\u0627\u0633\u0628 \u0647\u0633\u062a\u0646\u062f. \u0627\u0645\u0627 \u0627\u06af\u0631 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u06cc\u06a9 \u0634\u0631\u0648\u0639 \u0633\u0631\u06af\u0631\u0645\u200c\u06a9\u0646\u0646\u062f\u0647 \u0648 \u06af\u0627\u0645\u200c\u0628\u0647\u200c\u06af\u0627\u0645 \u0647\u0633\u062a\u06cc\u062f\u060c \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u06af\u0632\u06cc\u0646\u0647 \u0628\u0647\u062a\u0631\u06cc \u0627\u0633\u062a. \u0627\u06af\u0631 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u06cc\u062f \u0627\u0632 \u0647\u0645\u0627\u0646 \u0627\u0628\u062a\u062f\u0627 \u0628\u0631 \u0645\u06a9\u0627\u0644\u0645\u0647 \u062a\u0645\u0631\u06a9\u0632 \u06a9\u0646\u06cc\u062f\u060c \u0628\u0648\u0633\u0648 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u0646\u0627\u0633\u0628\u06cc \u0628\u0627\u0634\u062f.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%A8%D9%88%D8%B3%D9%88_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%B3%D8%B7%D9%88%D8%AD_%D9%BE%DB%8C%D8%B4%D8%B1%D9%81%D8%AA%D9%87%E2%80%8C_%D8%A8%D9%87%D8%AA%D8%B1_%D8%A7%D8%B3%D8%AA_%DB%8C%D8%A7_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88%D8%9F\"><\/span><span style=\"color: #36bf36;\">\u0628\u0648\u0633\u0648 \u0628\u0631\u0627\u06cc \u0633\u0637\u0648\u062d \u067e\u06cc\u0634\u0631\u0641\u062a\u0647\u200c \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u06cc\u0627 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648\u061f<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0628\u0631\u0627\u06cc \u0633\u0637\u0648\u062d \u067e\u06cc\u0634\u0631\u0641\u062a\u0647\u200c\u062a\u0631\u060c \u0628\u0648\u0633\u0648 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0645\u062d\u062a\u0648\u0627\u06cc \u063a\u0646\u06cc\u200c\u062a\u0631 \u0648 \u0627\u0645\u06a9\u0627\u0646 \u062a\u0639\u0627\u0645\u0644 \u0628\u0627 \u0632\u0628\u0627\u0646\u200c\u0622\u0645\u0648\u0632\u0627\u0646 \u062f\u06cc\u06af\u0631\u060c \u06af\u0632\u06cc\u0646\u0647 \u0645\u0646\u0627\u0633\u0628\u200c\u062a\u0631\u06cc \u0627\u0633\u062a.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%DA%A9%D8%AF%D8%A7%D9%85_%DB%8C%DA%A9_%D9%85%D8%AD%D8%AA%D9%88%D8%A7%DB%8C_%D8%A2%D9%85%D9%88%D8%B2%D8%B4%DB%8C_%D9%85%D8%AA%D9%86%D9%88%D8%B9%E2%80%8C%D8%AA%D8%B1%DB%8C_%D8%AF%D8%A7%D8%B1%D8%AF%D8%8C_%D8%A8%D9%88%D8%B3%D9%88_%DB%8C%D8%A7_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88%D8%9F\"><\/span><span style=\"color: #36bf36;\">\u06a9\u062f\u0627\u0645 \u06cc\u06a9 \u0645\u062d\u062a\u0648\u0627\u06cc \u0622\u0645\u0648\u0632\u0634\u06cc \u0645\u062a\u0646\u0648\u0639\u200c\u062a\u0631\u06cc \u062f\u0627\u0631\u062f\u060c \u0628\u0648\u0633\u0648 \u06cc\u0627 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648\u061f<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0631\u0648\u06cc\u06a9\u0631\u062f \u06af\u06cc\u0645\u06cc\u0641\u06cc\u06a9\u06cc\u0634\u0646\u06cc \u062e\u0648\u062f\u060c \u062a\u0646\u0648\u0639 \u0628\u06cc\u0634\u062a\u0631\u06cc \u062f\u0631 \u0627\u0646\u0648\u0627\u0639 \u062a\u0645\u0631\u06cc\u0646\u200c\u0647\u0627 \u0648 \u0628\u0627\u0632\u06cc\u200c\u0647\u0627 \u062f\u0627\u0631\u062f. \u0628\u0648\u0633\u0648 \u0646\u06cc\u0632 \u0645\u062d\u062a\u0648\u0627\u06cc \u0645\u062a\u0646\u0648\u0639\u06cc \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f\u060c \u0627\u0645\u0627 \u062a\u0645\u0631\u06a9\u0632 \u0622\u0646 \u0628\u06cc\u0634\u062a\u0631 \u0628\u0631 \u0645\u06a9\u0627\u0644\u0645\u0647 \u0648 \u062a\u0639\u0627\u0645\u0644 \u0627\u0633\u062a.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%A8%D9%88%D8%B3%D9%88_%D8%AA%D8%B9%D8%A7%D9%85%D9%84_%D8%A8%D8%A7_%D8%B2%D8%A8%D8%A7%D9%86%E2%80%8C%D8%A2%D9%85%D9%88%D8%B2%D8%A7%D9%86_%D8%AF%DB%8C%DA%AF%D8%B1_%D8%B1%D8%A7_%D8%A8%D9%87%D8%AA%D8%B1_%D9%81%D8%B1%D8%A7%D9%87%D9%85_%D9%85%DB%8C%E2%80%8C%DA%A9%D9%86%D8%AF_%DB%8C%D8%A7_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88%D8%9F\"><\/span><span style=\"color: #36bf36;\">\u0628\u0648\u0633\u0648 \u062a\u0639\u0627\u0645\u0644 \u0628\u0627 \u0632\u0628\u0627\u0646\u200c\u0622\u0645\u0648\u0632\u0627\u0646 \u062f\u06cc\u06af\u0631 \u0631\u0627 \u0628\u0647\u062a\u0631 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc\u200c\u06a9\u0646\u062f \u06cc\u0627 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648\u061f<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0628\u0648\u0633\u0648 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u062a\u0645\u0631\u06a9\u0632 \u0628\u0631 \u0645\u06a9\u0627\u0644\u0645\u0647 \u0648 \u0648\u062c\u0648\u062f \u0627\u0646\u062c\u0645\u0646\u200c\u0647\u0627\u06cc \u0622\u0646\u0644\u0627\u06cc\u0646\u060c \u0627\u0645\u06a9\u0627\u0646 \u062a\u0639\u0627\u0645\u0644 \u0628\u06cc\u0634\u062a\u0631\u06cc \u0628\u0627 \u0632\u0628\u0627\u0646\u200c\u0622\u0645\u0648\u0632\u0627\u0646 \u062f\u06cc\u06af\u0631 \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%A2%DB%8C%D8%A7_%D8%A8%D9%88%D8%B3%D9%88_%D9%88_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88_%D8%B1%D8%A7%DB%8C%DA%AF%D8%A7%D9%86_%D9%87%D8%B3%D8%AA%D9%86%D8%AF_%D9%88_%DB%8C%D8%A7_%D9%86%DB%8C%D8%A7%D8%B2_%D8%A8%D9%87_%D9%BE%D8%B1%D8%AF%D8%A7%D8%AE%D8%AA_%D8%A7%D8%B4%D8%AA%D8%B1%D8%A7%DA%A9_%D8%AF%D8%A7%D8%B1%D9%86%D8%AF%D8%9F\"><\/span><span style=\"color: #36bf36;\">\u0622\u06cc\u0627 \u0628\u0648\u0633\u0648 \u0648 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u0631\u0627\u06cc\u06af\u0627\u0646 \u0647\u0633\u062a\u0646\u062f \u0648 \u06cc\u0627 \u0646\u06cc\u0627\u0632 \u0628\u0647 \u067e\u0631\u062f\u0627\u062e\u062a \u0627\u0634\u062a\u0631\u0627\u06a9 \u062f\u0627\u0631\u0646\u062f\u061f<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0647\u0631 \u062f\u0648 \u067e\u0644\u062a\u0641\u0631\u0645 \u0646\u0633\u062e\u0647 \u0631\u0627\u06cc\u06af\u0627\u0646 \u0648 \u067e\u0648\u0644\u06cc \u062f\u0627\u0631\u0646\u062f. \u0646\u0633\u062e\u0647 \u0631\u0627\u06cc\u06af\u0627\u0646 \u0647\u0631 \u062f\u0648 \u067e\u0644\u062a\u0641\u0631\u0645 \u0627\u0645\u06a9\u0627\u0646\u0627\u062a \u0645\u062d\u062f\u0648\u062f\u06cc \u0631\u0627 \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%DA%A9%D8%AF%D8%A7%D9%85_%DB%8C%DA%A9_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%A7%D9%81%D8%B1%D8%A7%D8%AF%DB%8C_%DA%A9%D9%87_%D9%88%D9%82%D8%AA_%DA%A9%D9%85%DB%8C_%D8%AF%D8%A7%D8%B1%D9%86%D8%AF_%D9%85%D9%86%D8%A7%D8%B3%D8%A8%E2%80%8C%D8%AA%D8%B1_%D8%A7%D8%B3%D8%AA%D8%8C_%D8%A8%D9%88%D8%B3%D9%88_%DB%8C%D8%A7_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88%D8%9F\"><\/span><span style=\"color: #36bf36;\">\u06a9\u062f\u0627\u0645 \u06cc\u06a9 \u0628\u0631\u0627\u06cc \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u0648\u0642\u062a \u06a9\u0645\u06cc \u062f\u0627\u0631\u0646\u062f \u0645\u0646\u0627\u0633\u0628\u200c\u062a\u0631 \u0627\u0633\u062a\u060c \u0628\u0648\u0633\u0648 \u06cc\u0627 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648\u061f<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0647\u0631 \u062f\u0648 \u067e\u0644\u062a\u0641\u0631\u0645 \u0627\u0645\u06a9\u0627\u0646 \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u062f\u0631 \u0632\u0645\u0627\u0646\u200c\u0647\u0627\u06cc \u06a9\u0648\u062a\u0627\u0647 \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0627\u0645\u0627 \u0627\u06af\u0631 \u0648\u0642\u062a \u0628\u0633\u06cc\u0627\u0631 \u06a9\u0645\u06cc \u062f\u0627\u0631\u06cc\u062f\u060c \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u062a\u0645\u0631\u06cc\u0646\u200c\u0647\u0627\u06cc \u06a9\u0648\u062a\u0627\u0647\u200c\u062a\u0631 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u06af\u0632\u06cc\u0646\u0647 \u0628\u0647\u062a\u0631\u06cc \u0628\u0627\u0634\u062f.<\/p>\n<div class=\"sticky-bottom\">\r\n            \r\n                <div class=\"card\">\r\n\t\t\t\t  <div class=\"discount-badge\">49% \u062a\u062e\u0641\u06cc\u0641<\/div>\r\n                    <div class=\"image-content\">\r\n                        <img decoding=\"async\" src=\"https:\/\/accbazar.com\/thumbnails\/Duolingo-Plus\/Account-Duolingo-Premium.jpg\" alt=\"Product Image\">\r\n                    <\/div>\r\n                    <div class=\"text-content\">\r\n                        \r\n                            <h2 class=\"product-name\"><span class=\"ez-toc-section\" id=\"%D8%A7%DA%A9%D8%A7%D9%86%D8%AA_%D8%AF%D9%88%D9%84%DB%8C%D9%86%DA%AF%D9%88_%D9%BE%D9%84%D8%A7%D8%B3\"><\/span>\u0627\u06a9\u0627\u0646\u062a \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u067e\u0644\u0627\u0633<span class=\"ez-toc-section-end\"><\/span><\/h2>\r\n                            <p>     Duolingo Plus<\/p>\r\n                       \r\n                        <div class=\"price-button-section\">\r\n                            <div class=\"price-section\">\r\n\t\t\t\t\t\t\t<span class=\"old-price\">797,000 \u062a\u0648\u0645\u0627\u0646<\/span>\r\n                            <span class=\"new-price\">397,000 \u062a\u0648\u0645\u0627\u0646<\/span>\r\n\t\t\t\t\t\t\t<\/div>\r\n                            <a href=\"https:\/\/accbazar.com\/product\/Duolingo-Plus?utm_source=Blog&#038;utm_medium=Product&#038;utm_campaign=Blog\" class=\"buy-button\">\u0645\u0634\u0627\u0647\u062f\u0647 \u0648 \u062e\u0631\u06cc\u062f <\/a>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>","protected":false},"excerpt":{"rendered":"<p>\u0645\u0642\u0627\u06cc\u0633\u0647 \u0627\u0634\u062a\u0631\u0627\u06a9 \u0628\u0648\u0633\u0648 \u0648 \u0627\u0634\u062a\u0631\u0627\u06a9 \u062f\u0648\u0644\u06cc\u0646\u06af\u0648 \u067e\u0644\u0627\u0633\u061b \u0642\u062f\u0631\u062a\u0645\u0646\u062f\u062a\u0631\u06cc\u0646 \u0627\u0628\u0632\u0627\u0631 \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0632\u0628\u0627\u0646 \u06a9\u062f\u0627\u0645 \u0627\u0633\u062a\u061f \u0627\u0645\u0631\u0648\u0632\u0647 \u0628\u0627 \u06af\u0648\u0634\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u0648 \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u060c \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0632\u0628\u0627\u0646 \u0628\u0633\u06cc\u0627\u0631 \u0633\u0627\u062f\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a! \u0627\u0645\u0627 \u0628\u0627 \u0647\u0645\u0647 \u0627\u06cc\u0646 \u0627\u0648\u0635\u0627\u0641\u060c \u0627\u0646\u062a\u062e\u0627\u0628 \u0628\u0631\u0646\u0627\u0645\u0647 \u0645\u0646\u0627\u0633\u0628 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u06af\u06cc\u062c\u200c\u06a9\u0646\u0646\u062f\u0647 \u0628\u0627\u0634\u062f. \u0627\u0645\u0627 \u0646\u06af\u0631\u0627\u0646 \u0646\u0628\u0627\u0634\u06cc\u062f! \u0645\u0627 \u062f\u0631 \u0627\u06a9\u0627\u0646\u062a \u0628\u0627\u0632\u0627\u0631\u060c \u0641\u0631\u0648\u0634\u06af\u0627\u0647 \u062a\u062e\u0635\u0635\u06cc \u0641\u0631\u0648\u0634 \u0627\u06a9\u0627\u0646\u062a \u0647\u0627\u06cc \u0627\u0635\u06cc\u0644 \u0648 \u0642\u0627\u0646\u0648\u0646\u06cc\u060c \u062f\u0648 \u0628\u0631\u0646\u0627\u0645\u0647 \u0645\u062d\u0628\u0648\u0628 \u0622\u0645\u0648\u0632\u0634<\/p>\n","protected":false},"author":6,"featured_media":25572,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[110,1,15],"tags":[],"class_list":{"0":"post-25533","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-blog","8":"category-accbazar-mag","9":"category-learning-services"},"views":895,"_links":{"self":[{"href":"https:\/\/accbazar.com\/mag\/wp-json\/wp\/v2\/posts\/25533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accbazar.com\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accbazar.com\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accbazar.com\/mag\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/accbazar.com\/mag\/wp-json\/wp\/v2\/comments?post=25533"}],"version-history":[{"count":5,"href":"https:\/\/accbazar.com\/mag\/wp-json\/wp\/v2\/posts\/25533\/revisions"}],"predecessor-version":[{"id":26319,"href":"https:\/\/accbazar.com\/mag\/wp-json\/wp\/v2\/posts\/25533\/revisions\/26319"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accbazar.com\/mag\/wp-json\/wp\/v2\/media\/25572"}],"wp:attachment":[{"href":"https:\/\/accbazar.com\/mag\/wp-json\/wp\/v2\/media?parent=25533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accbazar.com\/mag\/wp-json\/wp\/v2\/categories?post=25533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accbazar.com\/mag\/wp-json\/wp\/v2\/tags?post=25533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}